{"id":11125,"date":"2025-11-10T05:28:19","date_gmt":"2025-11-10T05:28:19","guid":{"rendered":"https:\/\/www.marathit.com\/sex-story\/?p=11125"},"modified":"2025-11-10T05:28:32","modified_gmt":"2025-11-10T05:28:32","slug":"%e0%a4%ae%e0%a4%be%e0%a4%ae%e0%a5%80-%e0%a4%ac%e0%a4%a8%e0%a4%b2%e0%a5%80-%e0%a4%ac%e0%a4%be%e0%a4%af%e0%a4%95%e0%a5%8b-2","status":"publish","type":"post","link":"https:\/\/www.marathit.com\/sex-story\/%e0%a4%ae%e0%a4%be%e0%a4%ae%e0%a5%80-%e0%a4%ac%e0%a4%a8%e0%a4%b2%e0%a5%80-%e0%a4%ac%e0%a4%be%e0%a4%af%e0%a4%95%e0%a5%8b-2\/","title":{"rendered":"\u092e\u093e\u092e\u0940 \u092c\u0928\u0932\u0940 \u092c\u093e\u092f\u0915\u094b"},"content":{"rendered":"<div id=\"marat-509185494\" class=\"marat-before-content marat-entity-placement\"><div data-banner-id=\"1490361\"><\/div><\/div>\n<p>\u0928\u092e\u0938\u094d\u0915\u093e\u0930 \u092e\u093f\u0924\u094d\u0930\u093e\u0928\u094b \u092e\u093e\u091d\u093e \u092e\u093e\u0917\u091a\u093e \u0926\u094b\u0928 \u0938\u094d\u091f\u094b\u0930\u0940\u0928\u093e \u091a\u093e\u0902\u0917\u0932\u093e \u092a\u094d\u0930\u0924\u093f\u0938\u093e\u0926 \u0926\u093f\u0932\u094d\u092f\u093e\u092c\u0926\u094d\u0926\u0932 \u0927\u0928\u094d\u092f\u0935\u093e\u0926 \u090f\u0915 \u0928\u0935\u0940\u0928 \u0938\u094d\u091f\u094b\u0930\u0940 \u0918\u0947\u090a\u0928 \u0906\u0932\u094b\u092f \u0924\u0941\u092e\u091a\u093e \u0938\u093e\u0920\u0940 \u092e\u093e\u091d\u0902 \u0928\u093e\u0935 \u0936\u0941\u092d\u092e \u092e\u0940 \u0905\u0939\u093f\u0932\u094d\u092f\u093e\u0928\u0917\u0930 \u091a\u093e \u0906\u0939\u0947 \u092e\u0932\u093e \u092e\u0928\u0938\u094b\u0915\u094d\u0924 \u091d\u0935\u093e\u092f\u0932\u093e \u0916\u0942\u092a \u0906\u0935\u0921\u0924 \u0906\u091c \u0924\u0941\u092e\u094d\u0939\u093e\u0932\u093e \u092e\u093e\u091d\u0940 \u0906\u0923\u093f \u092e\u093e\u091d\u093e \u092e\u093e\u092e\u0940\u091a\u0940 \u0905\u091a\u093e\u0928\u0915 \u0918\u0921\u0932\u0947\u0932\u0940 \u0939\u0915\u0940\u0915\u0924 \u0938\u093e\u0902\u0917\u0928\u0930 \u0906\u0939\u0947&nbsp;<\/p>\n\n\n\n<p>\u092e\u093e\u091d\u0902 \u0935\u092f 24 \u0935\u0930\u094d\u0937 \u0906\u0939\u0947 \u0906\u0923\u093f \u092e\u093e\u091d\u093e \u092e\u093e\u092e\u0940\u091a\u0940 30 \u092e\u093e\u092e\u0940\u091a\u0947 \u0935\u0930\u094d\u0923\u0928 \u0938\u093e\u0902\u0917\u093e\u092f\u0932\u093e \u0917\u0947\u0932\u094b \u0924\u0930 32 30 24 \u091a\u0940 \u092b\u093f\u0917\u0930 \u0905\u0924\u094d\u092f\u0902\u0924 \u0906\u0915\u093e\u0930\u093e\u0924 \u092b\u0941\u0917\u0932\u0947\u0932\u0940 \u0917\u093e\u0902\u0921 \u0909\u092d\u093e\u0930\u0932\u0947\u0932\u0947 \u0938\u094d\u0924\u0928 \u0926\u093f\u0938\u093e\u092f\u0932\u093e \u0938\u093e\u0935\u0933\u0940 \u092a\u0923 \u0928\u093e\u0915\u093e \u0921\u094b\u0933\u094d\u092f\u093e\u0924 \u091b\u093e\u0928 \u0924\u0940 \u0928\u0947\u0939\u092e\u0940 \u0935\u0947\u0938\u094d\u091f\u0930\u094d\u0928 \u0915\u092a\u0921\u0947 \u0918\u093e\u0932\u0924\u0940 \u092e\u093e\u091d\u093e \u092e\u093e\u092e\u093e \u0907\u0902\u091c\u093f\u0928\u093f\u0905\u0930 \u0906\u0939\u0947 \u0906\u0923\u093f \u090f\u0915\u093e \u092e\u094b\u0920\u094d\u092f\u093e \u0915\u0902\u092a\u0928\u0940 \u092e\u0927\u094d\u092f\u0947 \u0915\u093e\u092e \u0915\u0930\u0924\u094b \u092e\u093e\u092e\u093e \u0932\u093e \u0928\u0947\u0939\u092e\u0940 \u0907\u0915\u0921\u0947 \u0924\u093f\u0915\u0921\u0947 \u092c\u093e\u0939\u0947\u0930 \u0917\u093e\u0935\u0940 \u091c\u093e\u0935\u093e \u0932\u093e\u0917\u0924 \u092e\u093e\u092e\u0940 \u090f\u0915\u091f\u0940\u091a \u0905\u0938\u0924\u0947 \u0918\u0930\u0940 \u0924\u093f\u091a\u093e \u092e\u0941\u0932\u0917\u093e \u0932\u0939\u093e\u0928 \u0906\u0939\u0947 8 \u0935\u0930\u094d\u0937\u093e\u091a\u093e \u0924\u094d\u092f\u093e\u0932\u093e \u0918\u0947\u090a\u0928 \u0930\u093e\u0939\u0924\u0947 \u092e\u093e\u092e\u0940 \u091a\u0940 \u0909\u0902\u091a\u0940 \u0915\u092e\u0940 \u0906\u0939\u0947 \u092e\u093e\u091d\u0940 \u0915\u093e\u0935\u0933\u094d\u092f\u093e \u092e\u0941\u0932\u0940 \u0938\u093e\u0930\u0916\u0940 \u0926\u093f\u0938\u0924\u0947.<\/p>\n\n\n\n<p>\u0924\u0930 \u090f\u0915\u0926\u093e \u092e\u093e\u092e\u093e \u091a\u093e \u0917\u093e\u0935\u093e\u0932\u093e \u092d\u093e\u0902\u0921\u0923 \u091d\u093e\u0932\u0947 \u0939\u094b\u0924\u0947 \u0936\u0947\u091c\u093e\u0931\u094d\u092f\u093e\u0902\u0928 \u0938\u094b\u092c\u0924 \u0924\u0930 \u092e\u093e\u092e\u093e \u0928\u0947 \u0918\u0930 \u0916\u093e\u0932\u0940 \u0915\u0947\u0932\u0947 \u0906\u0923\u093f \u0906\u092e\u091a\u093e \u0907\u0915\u0921\u0947 \u0928\u0917\u0930 \u0932\u093e \u0906\u0932\u0947&nbsp;<\/p>\n\n\n\n<p>\u092e\u093e\u092e\u093e \u0918\u0930\u0940 \u092f\u0947\u090a\u0928 \u092c\u0938\u0932\u0947 \u092e\u093e\u092e\u0940 \u092a\u0923 \u0938\u094b\u092c\u0924 \u0939\u094b\u0924\u094d\u092f\u093e \u0926\u094b\u0918 \u0939\u0940 \u0918\u093e\u092c\u0930\u0932\u094d\u092f\u093e \u0938\u093e\u0930\u0916\u0947 \u0939\u094b\u0924\u0947 \u0924\u0930 \u0918\u0930\u093e\u0924 \u092f\u0947\u090a\u0928 \u092e\u092e\u094d\u092e\u0940 \u092a\u092a\u094d\u092a\u093e \u0932\u093e \u0938\u0930\u094d\u0935 \u0915\u093e\u0939\u0940 \u0938\u093e\u0902\u0917\u093f\u0924\u0932\u0947 \u092e\u092e\u094d\u092e\u0940 \u0906\u0923\u093f \u092a\u092a\u094d\u092a\u093e \u0928\u0947 \u0924\u094d\u092f\u093e\u0902\u0928\u093e \u0906\u0920 \u0926\u093f\u0935\u0938 \u0907\u0925\u091a \u0930\u093e\u0939\u093e\u092f\u093e\u0932\u093e \u0938\u093e\u0902\u0917\u093f\u0924\u0932\u0947 \u092e\u0940 \u092e\u092e\u094d\u092e\u0940 \u092a\u092a\u094d\u092a\u093e \u0906\u0923\u093f \u092e\u0940 \u0924\u093f\u0918\u093e\u091a \u0905\u0938\u0924\u094b\u0924 \u0918\u0930\u0940 \u092e\u092e\u094d\u092e\u0940 \u0939\u0940 \u091c\u0949\u092c \u0932\u093e \u091c\u093e\u0924\u0947 \u0906\u0923\u093f \u092a\u092a\u094d\u092a\u093e \u092a\u0923 \u0924\u0947\u0935\u094d\u0939\u093e \u092e\u0940 \u092a\u0923 \u0915\u0949\u0932\u0947\u091c \u0915\u0930\u093e\u092f\u091a\u094b.<\/p>\n\n\n\n<p>&nbsp;\u0906\u0924\u093e 2 \u0926\u093f\u092c\u0938 \u092e\u093e\u092e\u0940 \u092e\u0941\u0933\u0947 \u092e\u092e\u094d\u092e\u0940 \u0928\u093e\u0939\u0940 \u0917\u0947\u0932\u0940 \u091c\u0949\u092c \u0932\u093e \u092a\u0923 \u092e\u093e\u092e\u0940 \u092c\u094b\u0932\u0932\u094d\u092f\u093e \u0924\u093e\u0908 \u091c\u093e \u0924\u0941\u092e\u094d\u0939\u0940 \u091c\u0949\u092c \u0932\u093e \u092e\u0940 \u0925\u093e\u0902\u092c\u0923\u0902 \u0918\u0930\u0940 \u0924\u094d\u092f\u093e \u0926\u093f\u0935\u0936\u0940 \u092e\u092e\u094d\u092e\u0940 \u0917\u0947\u0932\u0940 \u091c\u0949\u092c \u0932\u093e \u0906\u0923\u093f \u092a\u092a\u094d\u092a\u093e \u0939\u0940 \u092e\u093e\u092e\u093e \u092e\u093e\u092e\u0940 \u0906\u0923\u093f \u092e\u0940\u091a \u0918\u0930\u0940 \u0939\u094b\u0924\u094b \u0906\u0923\u093f \u0924\u094d\u092f\u093e\u091a\u093e \u091b\u094b\u091f\u093e \u092e\u0941\u0932\u0917\u093e \u0905\u091a\u093e\u0928\u0915 \u092e\u093e\u092e\u093e \u0932\u093e \u0939\u0940 \u0911\u092b\u093f\u0938 \u091a\u0940 \u090f\u0915 \u092e\u0940\u091f\u093f\u0902\u0917 \u0938\u093e\u0920\u0940 \u0915\u0949\u0932 \u0906\u0932\u093e \u092e\u093e\u092e\u093e \u0939\u0940 \u0930\u093e\u0924\u094d\u0930\u0940 \u0909\u0926\u094d\u092f\u093e \u092f\u0947\u0924\u094b \u092c\u094b\u0932\u0942\u0928 \u0917\u0947\u0932\u0947 \u092e\u093e\u092e\u0940 \u092c\u094b\u0930 \u0939\u094b\u0909 \u0928\u092f\u0947 \u092e\u094d\u0939\u0923\u0942\u0928 \u092e\u0940 \u092e\u093e\u092e\u0940 \u0936\u0940 \u092c\u094b\u0932\u0924 \u092c\u0938\u0932\u094b \u092e\u093e\u092e\u0940 \u0906\u0923\u093f \u092e\u093e\u091d\u093e \u0917\u092a\u094d\u092a\u093e \u0916\u0942\u092a \u0930\u0902\u0917\u0932\u094d\u092f\u093e \u0906\u092e\u091a\u0947 \u0916\u0942\u092a \u0935\u0947\u0933 \u092c\u094b\u0932\u0923\u0947 \u091a\u093e\u0932\u0942 \u0939\u094b\u0924\u0947 \u092e\u0927\u0947\u091a \u092e\u093e\u091d\u0940 \u0928\u091c\u0930 \u092e\u093e\u092e\u0940 t shirt \u0935\u0930 \u091c\u093e\u092f\u091a\u0940 \u0924\u094d\u092f\u093e\u0902\u0928\u0940 \u0906\u0924\u0942\u0928 \u092c\u094d\u0930\u093e \u0928\u0935\u0924\u0940 \u0918\u093e\u0924\u0932\u0940 \u0924\u094d\u092f\u093e\u092e\u0941\u0933\u0947 \u0924\u094d\u092f\u093e\u0902\u091a\u0947 \u092c\u0949\u0932 \u0916\u0942\u092a \u0939\u0932\u092f\u091a\u0947&nbsp;<\/p>\n\n\n\n<p>\u092c\u0918\u0942\u0928 \u092e\u093e\u091d\u093e \u092c\u0941\u0932\u094d\u0932\u093e\u091a \u0909\u0920\u0932\u093e \u092e\u0940 \u091d\u093e\u0915\u093e\u092f\u0932\u093e \u092a\u094d\u0930\u092f\u0924\u094d\u0928 \u0915\u0930\u0924 \u0939\u094b\u0924\u094b \u092a\u0923 \u0915\u0902\u091f\u094d\u0930\u094b\u0932 \u0939\u094b\u0908\u0928\u093e \u092e\u0940 \u092e\u093e\u092e\u0940 \u0932\u093e \u092c\u094b\u0932\u0932\u094b \u092e\u093e\u092e\u0940 \u092e\u0940 \u092c\u093e\u0925\u0930\u0942\u092e \u0932\u093e \u091c\u093e\u090a\u0928 \u092f\u0947\u0924\u094b \u092e\u093e\u092e\u0940 \u092c\u094b\u0932\u0940 \u0939\u0940 \u092f\u093e \u0932\u0935\u0915\u0930 \u092e\u0940 \u0909\u0920\u0942\u0928 \u092c\u093e\u0925\u0930\u0942\u092e \u092e\u0927\u0947 \u0917\u0947\u0932\u094b \u091f\u0949\u092f\u0932\u0947\u091f \u0906\u0923\u093f \u092c\u093e\u0925\u0930\u0942\u092e \u090f\u0915\u0924\u094d\u0930 \u0905\u0938\u0932\u094d\u092f\u093e\u092e\u0941\u0933\u0947 \u092e\u093e\u092e\u0940 \u0928\u0947 \u0906\u0924\u091a \u0906\u0902\u0918\u094b\u0933 \u0915\u0930\u0942\u0928 \u0932\u091f\u0915\u0935\u0932\u0947\u0932\u0940 \u092c\u094d\u0930\u093e \u0926\u093f\u0938\u0932\u0940 \u0906\u0923\u093f \u092a\u0945\u091f\u0940 \u092a\u0923 \u0932\u093e\u0932 \u0930\u0902\u0917\u093e\u091a\u0940 \u092c\u094d\u0930\u093e \u0915\u0938\u0932\u0940 \u0939\u0949\u091f \u0939\u094b\u0924\u0940 \u092e\u0938\u094d\u0924 \u0938\u0941\u0917\u0902\u0927 \u0924\u093f\u091a\u093e \u092e\u0940 \u0918\u0947\u090a\u0928 \u0935\u093e\u0938 \u0918\u0947\u090a\u0928 \u0932\u093e\u0917\u0932\u094b \u091a\u093e\u091f\u0942 \u0932\u093e\u0917\u0932\u094b \u092e\u093e\u091d\u093e \u092c\u0941\u0932\u094d\u0932\u094d\u092f\u093e\u0935\u0930 \u0930\u0917\u0921\u0942 \u0932\u093e\u0917\u0932\u094b <\/p><div id=\"marat-3134515336\" class=\"marat-traffic marat-entity-placement\"><div id=\"ts_ad_native_mwggh\"><\/div>\r\n<script src=\"\/\/cdn.runative-syndicate.com\/sdk\/v1\/n.js\"><\/script>\r\n<script>\r\n   NativeAd({\r\n       element_id: \"ts_ad_native_mwggh\",\r\n       spot: \"ace439fc8add4bb78b9e03508bb1b8f7\",\r\n       type: \"label-under\",\r\n       cols: 4,\r\n       rows: 1,\r\n       title: \"Suggested for you\",\r\n       titlePosition: \"left\",\r\n       adsByPosition: \"right\",\r\n\tbreakpoints: [\r\n\t          {\r\n\t                    \"cols\": 2,\r\n\t                    \"width\": 770\r\n\t          }\r\n\t],\r\n        extid: \"{extid}\",\r\n   });\r\n<\/script><\/div>\n\n\n\n<p>\u0906\u0923\u093f \u0938\u0917\u0933\u0902 \u092a\u093e\u0923\u0940 \u092c\u094d\u0930\u093e \u0935\u0930 \u0915\u093e\u0922\u0932\u0902 \u092a\u0923 \u0924\u0947 \u0938\u093e\u092b \u0915\u0930\u093e\u092f\u091a\u0902 \u0932\u0915\u094d\u0937\u093e\u0924 \u091a \u0928\u093e\u0939\u0940 \u092e\u0940 \u092c\u093e\u0925\u0930\u0942\u092e \u091a\u093e \u092c\u093e\u0939\u0947\u0930 \u0906\u0932\u094b \u0924\u0947\u0935\u094d\u0939\u093e \u092e\u093e\u092e\u0940 \u0915\u093f\u091a\u0928 \u092e\u0927\u094d\u092f\u0947 \u091a\u0939\u093e \u092c\u0928\u0935\u0924 \u0939\u094b\u0924\u0940 \u092e\u093e\u0917\u0942\u0928 \u0916\u0942\u092a \u092e\u093e\u0932 \u0926\u093f\u0938\u0924 \u0939\u094b\u0924\u0940 \u0924\u093f\u091a\u0940 \u091f\u093e\u0908\u091f \u0932\u0948\u0917\u093f\u0902\u0938 \u092e\u0927\u0942\u0928 \u092e\u093e\u092e\u0940 \u091a\u0940 \u0917\u093e\u0902\u0921 \u0916\u0942\u092a \u0938\u094d\u092a\u0937\u094d\u091f \u0926\u093f\u0938\u0924 \u0939\u094b\u0924\u0940 \u092e\u0940 \u0924\u093f\u091a\u093e \u0917\u093e\u0902\u0921\u0940\u0915\u0921 \u092a\u093e\u0939\u0924 \u0939\u094b\u0924\u094b \u0924\u0947\u0935\u0922\u094d\u092f\u093e\u0924 \u092e\u093e\u092e\u0940 \u092e\u093e\u0917\u0947 \u0935\u0930\u093e\u0932\u0940 \u0924\u093f\u0928\u0947 \u092e\u093e\u091d\u093e \u0915\u0921 \u092a\u093e\u0939\u0924 \u0938\u094d\u092e\u093f\u0925 \u0939\u093e\u0938\u094d\u092f \u0926\u093f\u0932\u0947 \u0906\u0923\u093f \u092e\u094d\u0939\u0923\u093e\u0932\u0940 \u0906\u0932\u093e\u0924 \u0924\u0941\u092e\u094d\u0939\u0940 \u092c\u093e\u0939\u0947\u0930 \u0916\u0942\u092a \u0935\u0947\u0933 \u0932\u093e\u0935\u0932\u093e \u092e\u0940 \u0939\u0938\u0942\u0928 \u092c\u094b\u0932\u0932\u094b \u092e\u0932\u093e \u0916\u0942\u092a \u0935\u0947\u0933 \u0932\u093e\u0917\u0924\u094b \u0924\u094d\u092f\u093e\u0935\u0930 \u092e\u093e\u092e\u0940 \u0939\u0938\u0932\u0940 <\/p>\n\n\n\n<p>\u0906\u0923\u093f \u092e\u094d\u0939\u0923\u093e\u0932\u0940 \u0924\u0947\u091a \u092c\u0918\u093e\u092f\u091a\u0947 \u0906\u0939\u0947 \u092e\u0940 \u091c\u0930\u093e \u0935\u093f\u091a\u093e\u0930\u0924 \u092a\u0921\u0932\u094b \u0928\u0947\u092e\u0915\u0902 \u0915\u093e\u092f \u092e\u094d\u0939\u0923\u093e\u092f\u091a\u0902 \u0906\u0939\u0947 \u092e\u093e\u092e\u0940 \u0932\u093e \u092e\u0917 \u092e\u093e\u092e\u0940 \u0906\u0923\u093f \u092e\u0940 \u091a\u0939\u093e \u0918\u0947\u0924 \u0917\u092a\u094d\u092a\u093e \u091d\u093e\u0932\u094d\u092f\u093e \u092e\u093e\u092e\u0940 \u092e\u0932\u093e \u092c\u094b\u0932\u0932\u0940 \u0917\u0930\u094d\u0932\u092b\u094d\u0930\u0947\u0902\u0921 \u0935\u0917\u0948\u0930\u0947 \u0928\u093e\u0939\u0940 \u0915\u093e \u0936\u0941\u092d\u092e \u0924\u0941\u092e\u094d\u0939\u093e\u0932\u093e \u092e\u0940 \u092c\u094b\u0932\u0932\u094b \u0928\u093e\u0939\u0940 \u0928\u093e \u092e\u093e\u092e\u0940 \u0924\u0940 \u0939\u0938\u0924 \u092c\u094b\u0932\u0932\u0940 \u090f\u0935\u0922\u093e \u0924\u0930 \u091b\u093e\u0928 \u0926\u093f\u0938\u0924\u094b \u092e\u0917 \u0915\u093e \u0928\u093e\u0939\u0940 \u0917\u0930\u094d\u0932\u092b\u094d\u0930\u0947\u0902\u0921 \u0924\u0930 \u092e\u0940 \u092e\u094d\u0939\u091f\u0932\u0902 \u092e\u093e\u092e\u0940 \u0915\u0936\u093e\u0932\u093e \u091a\u0947\u0937\u094d\u091f\u093e \u0915\u0930\u0924\u093e \u0924\u0930 \u0924\u094d\u092f\u093e \u0939\u0938\u0942\u0928 \u092c\u094b\u0932\u0932\u094d\u092f\u093e \u0916\u0930\u091a \u092e\u0940 \u091c\u0930 \u0905\u0938\u0924\u0947 \u0924\u0930 \u0924\u0941\u092e\u094d\u0939\u093e\u0932\u093e \u0915\u0927\u0940\u091a \u0939\u094b \u092e\u094d\u0939\u0923\u093e\u0932\u0947 \u0905\u0938\u0924\u0947\u00a0<\/p>\n\n\n\n<p>\u00a0 \u0916\u0930\u0902 \u0915\u093e \u092e\u093e\u092e\u0940 \u0905\u0938 \u092c\u094b\u0932\u0942\u0928 \u092e\u0940 \ud83d\udcf1 \u092b\u094b\u0928 \u092c\u093e\u0939\u0947\u0930 \u0915\u093e\u0922\u0932\u093e \u0906\u0923\u093f \u092e\u093e\u092e\u0940 \u092c\u094b\u0932\u0940 \u092c\u0938\u093e \u092e\u0940 \u0906\u0932\u0947 \u0925\u094b\u0921\u094d\u092f\u093e \u0935\u0947\u0933\u093e\u0924 \u092e\u0917 \u092e\u093e\u092e\u0940 \u092c\u093e\u0925\u0930\u0942\u092e \u092e\u0927\u0947 \u0917\u0947\u0932\u0940 10 \u092e\u093f\u0928\u091f \u0928\u0947 \u092c\u093e\u0939\u0947\u0930 \u0906\u0932\u0940 \u0924\u093f\u091a\u0947 \u0939\u093e\u0924 \u092e\u093e\u0917\u0947 \u0939\u094b\u0924\u0947 \u092e\u093e\u091d\u0915\u0921 \u0930\u093e\u0917\u093e\u0924 \u092c\u0918\u0924 \u0906\u0932\u0940 \u0906\u0923\u093f \u092e\u0932\u093e \u092c\u094b\u0932\u0932\u0940 \u0939\u0940 \u0915\u093e\u092f \u092a\u0926\u094d\u0927\u0924 \u0906\u0939\u0947 \u0924\u0941\u092e\u094d\u0939\u0940 \u0939\u0947 \u0915\u093e\u092f \u0915\u0947\u0932\u0902 \u092e\u0940 \u0918\u093e\u092c\u0930\u0932\u094b \u0909\u0920\u0942\u0928 \u0909\u092d\u093e \u091d\u093e\u0932\u094b \u092e\u094d\u0939\u091f\u0932\u0902 \u0915\u093e \u0915\u093e&#8230; \u0915\u093e\u092f \u091d\u093e\u0932\u0902 \u092e\u093e\u092e\u0940 \u092e\u093e\u092e\u093e \u0928\u0947 \u092e\u0932\u093e \u092c\u094d\u0930\u093e \u0926\u093e\u0916\u0935\u0932\u0940 \u0906\u0923\u093f \u092e\u094d\u0939\u0923\u093e\u0932\u0940 \u0939\u0947 \u092c\u0918\u093e \u0916\u0942\u092a \u092e\u094b\u0920\u0947 \u091d\u093e\u0932\u093e\u0924 \u0915\u093e \u0939\u0947 \u0915\u093e\u092f \u0906\u0939\u0947 \u0924\u0941\u092e\u091a\u093e \u092e\u093e\u092e\u093e \u0932\u093e \u0926\u093e\u0916\u0935\u0924\u0947 \u0906\u0923\u093f \u0938\u0917\u0933 \u0938\u093e\u0902\u0917\u0924\u0947 \u092e\u0940 \u0918\u093e\u092c\u0930\u0942\u0928 \u092e\u093e\u092e\u0940 \u091a\u0947 \u092a\u093e\u092f \u092a\u0915\u0921\u0932\u0947 \u0906\u0923\u093f \u092e\u094d\u0939\u0923\u093e\u0932\u094b \u092e\u093e\u092e\u0940 \u0928\u0915\u093e \u0938\u093e\u0902\u0917\u0942 \u0928\u093e \u092a\u094d\u0932\u0940\u091c \u092e\u093e\u092e\u093e \u092e\u0932\u093e \u0916\u0941\u092a \u091a\u093e\u0902\u0917\u0932\u0902 \u0938\u092e\u091c\u0924\u093e\u0924 <\/p>\n\n\n\n<p>\u0906\u0923\u093f \u092a\u092a\u094d\u092a\u093e\u0932\u093e \u0915\u0933\u0932\u0902 \u0924\u0930 \u0924\u0947 \u092a\u0923 \u0916\u0942\u092a \u092e\u0930\u0924\u0940\u0932 \u092e\u0932\u093e \u092e\u093e\u092e\u0940 \u0928\u0947 \u092e\u0932\u093e \u0909\u0920\u0935\u0932\u0902 \u0906\u0923\u093f \u092c\u094b\u0932\u0932\u0940 \u0920\u0940\u0915 \u0906\u0939\u0947 \u092e\u0940 \u0915\u094b\u0923\u093e\u0932\u093e \u0938\u093e\u0902\u0917\u0923\u093e\u0930 \u0928\u093e\u0939\u0940 \u092a\u0923 \u092e\u0940 \u0938\u093e\u0902\u0917\u0947\u0932 \u0924\u0947 \u0915\u0930\u093e\u0935\u093e \u0932\u093e\u0917\u0947\u0932 \u0924\u0941\u092e\u094d\u0939\u093e\u0932\u093e \u092e\u0940 \u092c\u094b\u0932\u0932\u094b \u0939\u094b \u091a\u093e\u0932\u0947\u0932 \u092e\u094d\u0939\u0923\u0924\u093e\u0928 \u0924\u0947 \u0915\u0930\u0947\u0932 \u092e\u0940 \u092e\u093e\u092e\u0940 \u092c\u094b\u0932\u0940 \u0915\u093e\u0939\u0940 \u092a\u0923 \u0939\u093e \u092e\u0940 \u0939\u094b \u092e\u094d\u0939\u0923\u0942\u0928 \u0936\u093e\u0902\u0924 \u092c\u0938\u0932\u094b \u092e\u0917 \u092e\u093e\u092e\u0940 \u0918\u0930\u091a\u0940 \u0915\u093e\u092e\u0947 \u0915\u0930\u0942 \u0932\u093e\u0917\u0932\u0940 \u092e\u093e\u092e\u093e \u091a\u093e \u0915\u0949\u0932 \u0906\u0932\u093e \u092e\u093e\u092e\u093e \u092c\u094b\u0932\u0932\u0947 \u092e\u0940 \u0906\u091c \u0906\u0923\u093f \u0909\u0926\u094d\u092f\u093e \u092f\u0947\u0923\u093e\u0930 \u0928\u093e\u0939\u0940 \u0939\u0947 \u092a\u0930\u0935\u093e \u0930\u093e\u0924\u094d\u0930\u0940 \u092f\u0947\u0908\u0932 \u0905\u0930\u094d\u091c\u0902\u091f \u092e\u0941\u0902\u092c\u0908 \u0932\u093e \u091a\u093e\u0932\u0932\u094b\u092f \u092e\u093e\u092e\u0940 \u092e\u094d\u0939\u091f\u0932\u0940 \u0920\u0940\u0915 \u0906\u0939\u0947 <\/p><div id=\"marat-3578861699\" class=\"marat-content-2 marat-entity-placement\"><script src=\"https:\/\/ronracepub.com\/e\/base36\/49bz24o300podyqzz26i629nubo9hhynpe3duss012m29?width=300&height=250\" async type=\"text\/javascript\" charset=\"UTF-8\"><\/script><\/div>\n\n\n\n<p>\u0905\u0923\u093f \u092e\u093e\u091d\u094d\u0915\u0921 \u092f\u0947\u090a\u0928 \u092e\u0932\u093e \u0938\u093e\u0902\u0917\u0942 \u0932\u093e\u0917\u0932\u0940 \u0924\u093f\u0924\u0915\u094d\u092f\u093e\u0924 \u092e\u092e\u094d\u092e\u0940 \u092a\u092a\u094d\u092a\u093e \u0918\u0930\u0940 \u0906\u0932\u0947 \u092b\u094d\u0930\u0947\u0936 \u0939\u094b\u090a\u0928 \u092e\u092e\u094d\u092e\u0940 \u092e\u093e\u092e\u0940\u0932\u093e \u092e\u0926\u0924 \u0915\u0930\u0942 \u0932\u093e\u0917\u0932\u0940 \u0906\u0924\u093e \u092e\u093e\u092e\u0940\u0928\u0947 \u0932\u093e\u0932 \u0930\u0902\u0917\u093e\u091a\u0940 \u0938\u093e\u0921\u0940 \u0918\u093e\u0924\u0932\u0940 \u0939\u094b\u0924\u0940 \u0924\u0940 \u092e\u0941\u0926\u094d\u0926\u093e\u092e \u092e\u093e\u091d\u093e \u0938\u092e\u094b\u0930 \u0935\u093e\u0915\u0942\u0928 \u0915\u093e\u092e \u0915\u0930\u093e\u092f\u091a\u0940 \u092e\u0932\u093e \u0924\u093f\u091a\u0947 \u0928\u093f\u0924\u0902\u092c \u092a\u093e\u0939\u0942\u0928 \u0916\u0942\u092a \u091b\u093e\u0928 \u0935\u093e\u091f\u093e\u092f\u091a\u0947 \u0928\u0902\u0924\u0930 \u0924\u0940 \u092a\u0926\u0930 \u092a\u0921\u0942\u0928 \u0924\u093f\u091a\u0947 \u092c\u0949\u0932 \u0926\u093e\u0916\u0935\u0942 \u0932\u093e\u0917\u0932\u0940 \u092e\u0940 \u090f\u0915\u091f\u093e \u0930\u0942\u092e \u092e\u0927\u094d\u092f\u0947 \u092c\u0938\u0932\u094b \u0939\u094b\u0924\u094b \u0924\u0947\u0935\u094d\u0939\u093e \u092e\u093e\u092e\u0940 \u092e\u093e\u091d\u094d\u092f\u093e\u0915\u0921\u0947 \u0906\u0932\u0940 \u0906\u0923\u093f \u092e\u094d\u0939\u0923\u093e\u0932\u0940 \u0906\u091c \u092e\u0940 \u0915\u0936\u0940 \u0926\u093f\u0938\u0924\u0947 \u092e\u0940 \u092e\u094d\u0939\u091f\u0932\u0902 \u0916\u0942\u092a \u091b\u093e\u0928 \u0926\u093f\u0938\u0924\u093e\u0939\u0947\u0924 \u092e\u093e\u092e\u0940 \u0906\u0923\u093f \u092e\u093e\u092e\u0940 \u0939\u0938\u0932\u0940 \u0905\u0923\u093f \u092e\u094d\u0939\u091f\u0932\u0940 \u092e\u0940 \u092c\u094b\u0932\u0932\u0947 \u0932\u0915\u094d\u0937\u093e\u0924 \u0906\u0939\u0947 \u0928\u093e \u092e\u0940 \u0939\u094b \u092e\u094d\u0939\u091f\u0932\u0902 \u092e\u093e\u092e\u0940 \u092e\u094d\u0939\u091f\u0932\u0940 \u0909\u0926\u094d\u092f\u093e \u092c\u0918\u093e \u092e\u0917 \u0918\u0930\u0940 \u0930\u0939\u093e \u0915\u0949\u0932\u0947\u091c \u0932\u093e \u091c\u093e\u090a \u0928\u0915\u093e\u00a0<\/p>\n\n\n\n<p>\u092e\u0940 \u0935\u093f\u091a\u093e\u0930\u0924 \u092a\u0921\u0932\u094b \u0928\u0947\u092e\u0915\u0902 \u0915\u093e\u092f \u0938\u093e\u0902\u0917\u0923\u093e\u0930 \u0905\u0938\u0947\u0932 \u092e\u093e\u092e\u0940 \u0924\u0940 \u0928\u093f\u0918\u0942\u0928 \u0917\u0947\u0932\u0940 \u092e\u0940 \u091c\u0947\u0935\u0923 \u0915\u0947\u0932\u0902 \u0930\u0942\u092e \u092e\u0927\u094d\u092f\u0947 \u092b\u094b\u0928 \u092c\u0918\u0924 \u092e\u093e\u092e\u0940 \u0906\u0932\u0940 \u0906\u0924\u093e \u0924\u0940 \u0915\u092a\u0921\u0947 \u092c\u0926\u0932\u0942\u0928 \u092e\u094b\u0920\u094d\u092f\u093e \u0917\u0933\u094d\u092f\u093e\u091a\u093e \u0917\u093e\u090a\u0928 \u0918\u093e\u0932\u0942\u0928 \u0906\u0932\u0940 \u0926\u0930\u0935\u093e\u091c\u093e \u0909\u0918\u0921\u0932\u093e \u0906\u0923\u093f \u0906\u0924 \u092f\u0947\u090a\u0928 \u0913\u0922\u0923\u0940 \u091c\u0930\u093e \u0916\u093e\u0932\u0940 \u0915\u0947\u0932\u0940 \u092e\u093e\u091d\u093e \u0938\u092e\u094b\u0930 \u0916\u093e\u0932\u0940 \u0935\u093e\u0915\u0932\u0940 \u0924\u093e\u091f \u0918\u0947\u0908\u0932 \u0924\u0930 \u092e\u0932\u093e \u092a\u0942\u0930\u094d\u0923 \u092e\u094b\u0915\u0933\u0947 \u0924\u093f\u091a\u0947 \u092c\u0949\u0932 \u0926\u093f\u0938\u0924 \u0939\u094b\u0924\u0947 \u0924\u0940 \u0924\u0938\u0902\u091a 25 30 \u0938\u0947\u0915\u0902\u0926 \u0939\u094b\u0924\u0940 \u092e\u093e\u091d\u093e \u092c\u0941\u0932\u094d\u0932\u093e \u0916\u0942\u092a \u091f\u093e\u0908\u091f \u091d\u093e\u0932\u093e \u092e\u0940 \u0926\u093e\u092c\u0942 \u0932\u093e\u0917\u0932\u094b \u0932\u092a\u0935\u0942 \u0932\u093e\u0917\u0932\u094b \u092e\u093e\u092e\u0940 \u092c\u094b\u0932\u0940 \u0939\u093e \u0924\u0930 \u092b\u0915\u094d\u0924 \u091f\u094d\u0930\u0947\u0932\u0930 \u0939\u094b\u0924\u093e \u0909\u0926\u094d\u092f\u093e \u092a\u093e\u0939\u093e \u092e\u0940 \u0916\u0942\u092a \u0916\u0941\u0936 \u091d\u093e\u0932\u094b \u0915\u093e\u0930\u0923 \u092e\u093e\u092e\u0940 \u0938\u094d\u0935\u0924\u0903 \u0939\u093f\u092e\u094d\u092e\u0924 \u0915\u0930\u0924 \u0939\u094b\u0924\u0940 \u0930\u093e\u0924\u094d\u0930\u0940 \u091d\u094b\u092a\u093e\u092f\u091a\u0940 \u0935\u0947\u0933 \u091d\u093e\u0932\u0940 \u0906\u092e\u094d\u0939\u0940 \u0938\u0917\u0933\u0947 \u091d\u094b\u092a\u093e\u092f\u0932\u093e \u0917\u0947\u0932\u094b \u0906\u092a\u093e\u092a\u0932\u094d\u092f\u093e \u0930\u0942\u092e \u092e\u0927\u094d\u092f\u0947 \u092e\u093e\u092e\u0940 <\/p>\n\n\n\n<p>\u0906\u0923\u093f \u092e\u092e\u094d\u092e\u0940 \u091a\u0930\u094d\u091a\u093e \u0915\u0930\u0942 \u0932\u093e\u0917\u0932\u094d\u092f\u093e \u0915\u0940 \u092e\u092e\u094d\u092e\u0940 \u092c\u094b\u0932\u0940 \u0936\u0941\u092d\u092e \u091a\u093e \u092a\u092a\u094d\u092a\u093e\u0932\u093e \u0936\u0941\u092d\u092e \u091a\u093e \u0930\u0942\u092e \u092e\u0927\u0947 \u092a\u093e\u0920\u0935\u0924\u0947 \u0906\u0923\u093f \u0924\u0942 \u092e\u093e\u091d\u093e \u0930\u0942\u092e \u092e\u0927\u0947 \u091d\u094b\u092a \u0924\u0930 \u092e\u093e\u092e\u0940 \u092e\u094d\u0939\u0923\u093e\u0932\u0940 \u0915\u0940 \u0928\u093e\u0939\u0940 \u092e\u0940 \u091c\u093e\u0924\u0947 \u0936\u0941\u092d\u092e \u091a\u093e \u0930\u0942\u092e \u092e\u0927\u0947 \u092c\u092c\u0932\u0941 (\u092e\u093e\u092e\u0940\u091a\u093e \u092e\u0941\u0932\u0917\u093e) \u0906\u0923\u093f \u092e\u0940 \u0924\u093f\u0925\u0947\u091a \u091d\u094b\u092a\u0924\u094b \u092e\u092e\u094d\u092e\u0940 \u092c\u094b\u0932\u0932\u0940 \u0920\u0940\u0915 \u0906\u0939\u0947 \u091c\u093e \u0924\u0930 \u0930\u093e\u0924\u094d\u0930\u0940 11 \u0932\u093e \u092e\u093e\u092e\u0940 \u0906\u0923\u093f \u092c\u092c\u0932\u0941 \u092e\u093e\u091d\u093e \u0930\u0942\u092e \u092e\u0927\u094d\u092f\u0947 \u0906\u0932\u0947 \u092e\u0932\u093e \u0935\u093e\u091f\u0932\u0902 \u092c\u092c\u0932\u0941 \u092e\u0927\u0947 \u091d\u094b\u092a\u0947\u0932 \u092a\u0923 \u092e\u093e\u092e\u0940 \u092e\u0927\u0947 \u091d\u094b\u092a\u0932\u0940 \u092c\u0947\u0921 \u0935\u0930 \u092c\u092c\u0932\u0941 \u091d\u094b\u092a\u0942\u0928 \u0917\u0947\u0932\u093e \u092e\u093e\u092e\u0940 \u0924\u094d\u092f\u093e\u0932\u093e \u091d\u094b\u092a\u0935\u0942\u0928 \u092e\u093e\u091d\u0915\u0921 \u092a\u093e\u0920 \u0915\u0930\u0942\u0928 \u091d\u094b\u092a\u0932\u0940 \u092e\u0932\u093e \u0939\u0940 \u091d\u094b\u092a \u0932\u093e\u0917\u0932\u0940 \u0930\u093e\u0924\u094d\u0930\u0940\u091a\u0947 \u0926\u094b\u0928 \u0935\u093e\u091c\u0932\u0947 \u0939\u094b\u0924\u0947 \u092e\u0932\u093e \u091c\u093e\u0923\u0935\u0932\u0902 \u0915\u0940 \u0915\u093e\u0939\u0940 \u0924\u0930\u0940 \u0913\u0932 \u0932\u093e\u0917\u0924\u0902\u092f \u092e\u093e\u091d\u093e \u0932\u0935\u0921\u094d\u092f\u093e \u0932\u093e\u092e\u0940 \u0939\u0932\u0915\u0947 \u0921\u094b\u0933\u0947 \u0909\u0918\u0921\u0942\u0928 \u092a\u093e\u0939\u093f\u0932\u0902 \u0924\u0930 \u092e\u093e\u092e\u0940 \u0905\u0902\u0927\u093e\u0930\u093e\u0924 \u0935\u0930\u0924\u0940 \u0928\u0917\u094d\u0928 \u0939\u094b\u090a\u0928 \u0932\u093e\u0933 \u0917\u0933\u0942\u0928 \u092e\u093e\u091d\u093e \u092c\u0941\u0932\u094d\u0932\u093e \u0924\u094b\u0902\u0921\u093e\u0928\u0947 \u091a\u094b\u0933\u0924 \u092e\u093e\u091d\u093e \u0917\u094b\u091f\u094d\u092f\u093e \u0915\u0941\u0930\u0935\u093e\u0933\u0924 \u091d\u094b\u092a\u0932\u0940 \u0939\u094b\u0924\u0940 \u092e\u093e\u091d\u093e \u092c\u0941\u0932\u094d\u0932\u093e \u0924\u094b\u0902\u0921\u093e\u0928\u0947 \u091a\u094b\u0933\u0924 \u0939\u093e\u0924\u093e\u0928\u0947 \u0939\u0932\u0935\u0942 \u0932\u093e\u0917\u0932\u0940 <\/p>\n\n\n\n<p>\u092e\u0940 \u0906\u0939\u093e\u0939\u093e \u0915\u0930\u0924 \u0939\u094b\u0924\u094b \u0924\u0930 \u0924\u0940 \u0935\u0930 \u092f\u0947\u090a\u0928 \u092c\u0938\u0932\u0940 \u092c\u0949\u0932 \u092e\u093e\u091d\u093e \u091b\u093e\u0924\u0940\u0935\u0930 \u0920\u0947\u0935\u0942\u0928 \u0915\u093f\u0938 \u0915\u0930\u0942 \u0932\u093e\u0917\u0932\u0940 \u092e\u0940 \u0921\u094b\u0933\u0947 \u0909\u0918\u0921\u0932\u0947 \u0906\u0923\u093f \u0939\u0933\u0942 \u0906\u0935\u093e\u091c\u093e\u0924 \u092e\u094d\u0939\u091f\u0932\u0902 \u092e\u093e\u092e\u0940 \u0939\u0947 \u0915\u093e\u092f \u0915\u0930\u0924 \u0906\u0939\u0947\u0924 \u0924\u0930 \u092e\u093e\u092e\u0940 \u092c\u094b\u0932\u0932\u0940 \u091a\u0942\u092a \u0906\u0924\u093e \u0924\u0942\u091a \u092e\u093e\u091d\u093e \u0928\u0935\u0930\u093e \u0906\u0923\u093f \u0916\u093e\u0932\u0940 \u0939\u093e\u0924 \u0918\u093e\u0932\u0942\u0928 \u092e\u093e\u091d\u093e \u092c\u0941\u0932\u094d\u0932\u093e \u0926\u093e\u092c\u0942 \u0932\u093e\u0917\u0932\u0940 \u0906\u0903\u0902\u0939 \u0915\u0947\u0932\u0902 \u092e\u0940 \u0924\u0930 \u092e\u094d\u0939\u091f\u0932\u0940 \u0909\u0926\u094d\u092f\u093e \u0915\u0930\u0923\u093e\u0930 \u0939\u094b\u0924\u0947 \u092a\u0923 \u092e\u0932\u093e \u0915\u0902\u091f\u094d\u0930\u094b\u0932 \u0939\u094b\u0908\u0928\u093e \u0924\u0930 \u092e\u0940 \u0924\u093f\u091a\u0947 \u092c\u0949\u0932 \u091a\u094b\u0933\u0942 \u0932\u093e\u0917\u0932\u094b \u0924\u0940 \u0907\u0924\u0915\u0940 \u092b\u094d\u0930\u0947\u0936 \u0939\u094b\u0924\u0940 <\/p>\n\n\n\n<p>\u0924\u0940 \u092e\u093e\u091d\u093e \u0924\u094b\u0902\u0921\u093e\u0935\u0930 \u0905\u0939\u094d\u0939 \u0905\u0939\u094d\u0939 \u0915\u0930\u0942 \u0932\u093e\u0917\u0932\u0940 \u092e\u0932\u093e \u0924\u093f\u091a\u093e \u0924\u094b\u0902\u0921\u093e\u0924\u0942\u0928 \u0917\u093e\u0930 \u0939\u0935\u093e \u0932\u093e\u0917\u0924 \u0939\u094b\u0924\u0940 \u0907\u0924\u0915\u0940 \u092b\u094d\u0930\u0947\u0936 \u0915\u0940 \u0915\u0938\u0932\u093e\u0939\u0940 \u0935\u093e\u0938 \u092f\u0947\u0924\u0902 \u0928\u0935\u094d\u0939\u0924\u093e \u092e\u0932\u093e \u0924\u0940 \u092c\u0949\u0932 \u092a\u093e\u091c\u0942 \u0932\u093e\u0917\u0932\u0940 \u0924\u094d\u092f\u093e\u0924\u0942\u0928 \u0926\u0942\u0927 \u092f\u0947\u0924 \u0939\u094b\u0924\u0902 \u0916\u0942\u092a \u0935\u0947\u0933 \u092a\u093f\u0932\u094b \u0928\u0902\u0924\u0930 69 \u091a\u093e \u092a\u094b\u0938 \u092e\u0927\u0947 \u091c\u093e\u090a\u0928 \u0924\u093f\u091a\u0940 \u0917\u093e\u0902\u0921 \u091a\u093e\u091f\u093e\u092f\u0932\u093e \u0932\u093e\u0917\u0932\u094b \u0924\u0940 \u0916\u0942\u092a \u0917\u0930\u092e \u091d\u093e\u0932\u0940 \u0924\u093f\u0928\u0947 \u092e\u093e\u091d\u093e \u092a\u0941\u0930\u094d\u0923 \u092c\u0941\u0932\u094d\u0932\u093e \u0924\u094b\u0902\u0921\u093e\u0928\u0947 \u0918\u0947\u0924\u0932\u093e \u0924\u0940\u091a \u092a\u093e\u0923\u0940 \u092e\u093e\u091d\u093e \u0924\u094b\u0902\u0921\u093e\u0935\u0930 \u0917\u093e\u0933\u0932\u093e \u0938\u0917\u0933 \u091a\u093e\u091f\u0942\u0928 \u0918\u0947\u0924\u0932\u0902 \u092e\u0940 \u0924\u0940 \u0924\u093f\u091a\u0940 \u0917\u093e\u0902\u0921 \u0930\u0917\u0921\u0924 \u0939\u094b\u0924\u0940 \u0924\u094b\u0902\u0921\u093e\u0935\u0930 aaaah \u092e\u0940 \u0916\u0942\u092a \u091a\u093e\u091f\u0924 \u0939\u094b\u0924\u094b \u0936\u0947\u0935\u091f\u0940 \u092e\u093e\u092e\u0940 \u0928\u0947 \u092e\u093e\u091d\u0902 \u0939\u0940 \u092a\u093e\u0923\u0940 \u0915\u093e\u0922\u0932 \u090f\u0915 \u0925\u0947\u0902\u092c \u0916\u093e\u0932\u0940 \u0928\u093e\u0939\u0940 \u091c\u093e\u090a \u0926\u093f\u0932\u093e \u0906\u0939\u093e\u0939\u093e \u092e\u093e\u091d\u093e \u0939\u093e\u0924 <\/p>\n\n\n\n<p>\u0906\u0923\u093f \u092e\u093e\u092e\u0940\u091a\u0947 \u092c\u0949\u0932 \u0916\u0942\u092a \u091a\u094b\u0933\u0924 \u0939\u094b\u0924\u094b \u092e\u0917 \u092e\u0940 \u0906\u0923\u093f \u092e\u093e\u092e\u0940 \u0936\u0947\u091c\u093e\u0930\u0940 \u091d\u094b\u092a\u0942\u0928 \u0915\u093f\u0938 \u0915\u0930\u0942 \u0932\u093e\u0917\u0932\u094b \u092e\u093e\u092e\u0940 \u092e\u093e\u091d\u093e\u0936\u0940 \u092c\u094b\u0932\u0924 \u0915\u093f\u0938 \u0915\u0930\u0924 \u0939\u094b\u0924\u0940 \u092e\u093e\u092e\u0940 \u092c\u094b\u0932\u0932\u0940 \u0905\u0938\u091a \u092c\u0941\u0932\u094d\u0932\u093e \u092a\u093e\u0939\u093f\u091c\u0947 \u0939\u094b\u0924\u093e \u092e\u0932\u093e \u0924\u0941\u092e\u091a\u093e \u092e\u093e\u092e\u093e \u091a\u093e \u091c\u0930\u093e \u0932\u0939\u093e\u0928 \u0906\u0939\u0947 \u0924\u0941\u092e\u091a\u093e \u0915\u093f\u0924\u0940 \u092d\u093e\u0930\u0940 \u0906\u0939\u0947 6.5\u0907\u0902\u091a n \u0924\u094b\u0902\u0921\u093e\u0902\u0924 \u0924\u094b\u0902\u0921 \u0918\u093e\u0932\u0942\u0928 \u092c\u0941\u0932\u094d\u0932\u093e \u0939\u0932\u0935\u0942 \u0932\u093e\u0917\u0932\u0940 \u0926\u094b\u0918 \u092a\u0923 \u0905\u0902\u0927\u093e\u0930\u093e\u0924 \u0928\u0917\u094d\u0928 \u091d\u094b\u092a\u0932\u0947\u0932\u094b \u0915\u093f\u0938 \u0915\u0930\u0942\u0928 \u092e\u0940 \u092e\u093e\u092e\u0940 \u091a\u093e \u0935\u0930 \u0906\u0932\u094b \u092e\u093e\u092e\u0940 \u092c\u094b\u0932\u0932\u0940 \u0936\u0941\u092d\u092e \u0928\u0915\u093e \u0928\u093e \u0924\u0930\u0938\u093e\u0935\u0942 \u0918\u093e\u0932\u093e \u0928\u093e \u0924\u0941\u092e\u091a\u093e \u092c\u0941\u0932\u094d\u0932\u093e \u0906\u0903\u0902\u0939 \u0918\u093e\u0932\u093e \u0928\u093e \u0913 <\/p>\n\n\n\n<p>\u0906\u0923\u093f \u092e\u093e\u091d\u0902 \u0921\u094b\u0915\u0902 \u0927\u0930\u0942\u0928 \u0915\u0940\u0938 \u0915\u0930\u0942 \u0932\u093e\u0917\u0932\u0940 \u092e\u0940 \u0924\u093f\u091a\u093e \u092a\u093e\u0920\u0940\u091a\u093e \u0916\u093e\u0932\u0940 \u0939\u093e\u0924 \u0918\u093e\u0932\u0942\u0928 \u092a\u0915\u0921\u0932\u0902 \u0924\u093f\u0928\u0947 \u090f\u0915\u093e \u0939\u093e\u0924\u093e\u0928\u0947 \u092e\u093e\u091d\u093e \u092c\u0941\u0932\u094d\u0932\u093e \u091c\u093e\u092e \u0926\u093e\u092c\u0942\u0928 \u0927\u0930\u0932\u093e \u0906\u0923\u093f \u092a\u0941\u091a\u094d\u091a\u0940\u0935\u0930 \u0938\u0947\u091f \u0915\u0947\u0932\u093e \u092a\u0941\u091a\u094d\u091a\u0940 \u0913\u0932\u0940 \u0905\u0938\u0932\u094d\u092f\u093e \u092e\u0941\u0933\u0947 \u0918\u092a\u0915\u0928 \u092c\u0941\u0932\u094d\u0932\u093e \u0906\u0924 \u0918\u0941\u0938\u0932\u093e \u0924\u0938\u093e\u091a \u092e\u093e\u092e\u0940 \u0928\u0947 \u0906\u0903\u0902\u0939 \u0915\u0930\u0942\u0928 \u092e\u094d\u0939\u0923\u093e\u0932\u0940 \u092e\u0947\u0932\u0947 \u092e\u0940 \u0906\u0903\u0939 \u0916\u0942\u092a \u092e\u0938\u094d\u0924 \u0935\u093e\u091f\u0924\u0902\u092f \u092e\u0940 \u0939\u0933\u0942 \u0939\u0933\u0941 \u0926\u0923\u0915\u0947 \u0926\u0947\u0924 \u0939\u094b\u0924\u094b \u092e\u093e\u092e\u0940 \u092e\u093e\u091d\u093e \u0924\u094b\u0902\u0921\u093e\u0902\u0924 \u0924\u094b\u0902\u0921 \u0918\u093e\u0932\u0924 \u0939\u094b\u0924\u0940 \u092e\u093e\u091d\u093e \u092c\u0941\u0932\u094d\u0932\u093e \u0916\u0942\u092a \u091c\u093e\u0938\u094d\u0924 \u0932\u094b\u0916\u0902\u0921 \u0938\u093e\u0930\u0916\u093e \u0915\u0921\u0915 \u091d\u093e\u0932\u093e \u0916\u0942\u092a \u0906\u0930\u093e\u092e\u093e\u0924 \u0918\u0941\u0938\u0924 \u0939\u094b\u0924\u093e \u092e\u093e\u092e\u0940\u091a\u093e \u0926\u093e\u0923\u093e \u091a\u093f\u0930\u0942\u0928 \u0906\u0924 \u091c\u093e\u0924 \u0939\u094b\u0924\u093e \u092e\u093e\u092e\u0940 \u0924\u0921\u092a\u0921\u0942 \u0932\u093e\u0917\u0932\u0940 \u0906\u0923\u093f \u092e\u0932\u093e \u091f\u093e\u0907\u091f \u092a\u0915\u0921\u0942\u0928 \u092a\u0941\u091a\u094d\u091a\u0940 \u0924\u0942\u0928 \u092a\u093e\u0923\u0940 \u0915\u093e\u0922\u0942 \u0932\u093e\u0917\u0932\u0940 \u0916\u0942\u092a \u0906\u0928\u0902\u0926 \u092f\u0947\u0924 \u0939\u094b\u0924\u093e <\/p>\n\n\n\n<p>\u0906\u0939\u093e\u0939\u093e \u092e\u0917 \u092e\u0940 \u092c\u0941\u0932\u094d\u0932\u093e \u092c\u093e\u0939\u0947\u0930 \u0915\u093e\u0922\u0942\u0928 \u092e\u093e\u092e\u0940 \u0932\u093e \u0909\u0932\u091f\u0940 \u0915\u0947\u0932\u0940 \u0921\u0949\u0917\u0940 \u0938\u094d\u091f\u093e\u0908\u0932 \u092e\u0927\u094d\u092f\u0947 \u0906\u0923\u093f \u092e\u093e\u0917\u0942\u0928 \u092a\u0941\u091a\u094d\u091a\u0940\u0924 \u092c\u0941\u0932\u094d\u0932\u093e \u0918\u093e\u0924\u0932\u093e \u092e\u093e\u092e\u0940 \u0916\u0942\u092a \u0918\u093e\u092e\u093e\u0928\u0947 \u092d\u093f\u091c\u0932\u0940 \u0939\u094b\u0924\u0940 \u092e\u093e\u092e\u0940 \u091a \u0924\u0947 \u0930\u0942\u092a \u0905\u0935\u093f\u0938\u094d\u092e\u0930\u0923\u0940\u092f \u0939\u094b\u0924\u0947 \u092e\u093e\u091d\u093e \u0906\u092f\u0941\u0937\u094d\u092f\u093e\u0924 \u092a\u0939\u093f\u0932\u094d\u092f\u093e\u0902\u0926\u093e \u090f\u0935\u0922\u094d\u092f\u093e \u090f\u0915\u094d\u0938\u094d\u092a\u0947\u0930\u093f\u090f\u0928\u094d\u0938 \u0928\u0947 \u0915\u094b\u0923\u0940 \u0924\u0930\u0940 \u092e\u093e\u091d\u093e \u092c\u0941\u0932\u094d\u0932\u093e\u0928\u0947 \u091d\u0935\u0942\u0928 \u0918\u0947\u0924 \u0939\u094b\u0924 \u092e\u093e\u091d\u0940 2 \u0935\u0947\u0933 \u091d\u0921\u0932\u0940 \u0939\u094b\u0924\u0940 \u0906\u0923\u093f \u092e\u0940 \u090f\u0915\u0926\u093e \u0906\u0924\u093e \u092e\u093e\u091d\u093e \u092c\u093e\u0902\u0927 \u092b\u0941\u091f\u093e\u092f\u093e\u0932\u093e \u0939\u094b\u0924\u093e \u092e\u0940 \u092e\u093e\u092e\u0940 \u0932\u093e \u092c\u094b\u0932\u0932\u094b \u092e\u093e\u092e\u0940 \u092e\u093e\u091d\u0902 \u091c\u0935\u0933 \u0906\u0932\u0902 \u0906\u0939\u0947 \u092e\u093e\u092e\u0940 \u092c\u094b\u0932\u0932\u0940 \u092e\u093e\u091d\u093e \u092a\u0941\u091a\u094d\u091a\u0940\u0924 \u0938\u094b\u0921\u0942\u0928 \u091f\u093e\u0915 \u0938\u0917\u0933 \u0924\u0941\u091d\u0940 \u0930\u0902\u0921\u0940 \u092c\u0928\u0935 \u092e\u0932\u093e <\/p>\n\n\n\n<p>\u092e\u0940 \u092e\u094d\u0939\u091f\u0932\u0902 \u092e\u093e\u091d\u0940 \u0930\u0902\u0921\u0940 \u092e\u093e\u092e\u0940 \u092e\u0932\u093e \u0924\u0941\u091d\u093e \u0924\u094b\u0902\u0921\u093e\u0935\u0930 \u091f\u093e\u0915\u093e\u092f\u091a\u0902 \u0906\u0939\u0947 \u092e\u093e\u092e\u0940 \u092a\u091f\u0915\u0928 \u0909\u0920\u0942\u0928 \u092c\u0947\u0921 \u091a\u093e \u0916\u093e\u0932\u0940 \u0909\u0924\u0930\u0942\u0928 \u0924\u094b\u0902\u0921 \u092a\u0941\u0922 \u0915\u0930\u0942\u0928 \u092c\u0938\u0932\u0940 \u092e\u0940 \u0938\u0917\u0933 \u092a\u093e\u0923\u0940 \u0924\u093f\u091a\u093e \u0924\u094b\u0902\u0921\u093e\u0935\u0930 \u0915\u093e\u0922\u0932\u0902 \u0906\u0923\u093f \u0924\u0938\u093e\u091a \u092c\u0947\u0921 \u0935\u0930 \u092a\u0921\u0932\u094b \u092e\u093e\u092e\u0940 \u0932\u093e \u092e\u0940 \u0924\u094b\u0902\u0921\u093e\u0935\u0930\u091a \u092a\u093e\u0923\u0940 \u092e\u093e\u091d\u093e \u092c\u094b\u091f\u093e\u0928\u0947 \u092a\u093e\u091c\u0932\u093e \u0924\u094b\u0902\u0921 \u0938\u093e\u092b \u0915\u0930\u0942\u0928 \u0926\u093f\u0932 \u0906\u0923\u093f \u092e\u093e\u092e\u0940 \u0928\u0947 \u092e\u093e\u091d\u093e \u092c\u0941\u0932\u094d\u0932\u093e \u0924\u094b\u0902\u0921\u093e\u0928\u0947 \u091a\u093e\u091f\u0942\u0928 \u0938\u093e\u092b \u0915\u0947\u0932\u093e \u0924\u094d\u092f\u093e \u0926\u093f\u0935\u0936\u0940 \u092a\u0939\u093f\u0932\u094d\u092f\u093e\u0902\u0926\u093e \u090f\u0935\u0922\u0940 \u0939\u0935\u0938 \u0928\u0947 \u092d\u0930\u0932\u0947\u0932\u0940 \u0938\u094d\u0924\u094d\u0930\u0940 \u092a\u093e\u0939\u093f\u0932\u0940 \u0939\u094b\u0924\u0940 <\/p>\n\n\n\n<p>\u092e\u0940 \u0924\u094d\u092f\u093e \u0930\u093e\u0924\u094d\u0930\u0940 \u0905\u091c\u0942\u0928 2 \u0935\u0947\u0933\u093e \u092e\u093e\u092e\u0940\u0928\u0947 \u092e\u093e\u091d\u094d\u092f\u093e\u0915\u0921\u0942\u0928 \u091d\u0935\u0942\u0928 \u0918\u0947\u0924\u0932\u0902 \u0938\u0915\u093e\u0933\u0940 5 \u0932\u093e \u091d\u094b\u092a\u0932\u094b \u0906\u092e\u094d\u0939\u0940 \u092e\u093e\u092e\u0940 \u0938\u0915\u093e\u0933\u0940 7 \u0932\u093e \u0909\u0920\u0942\u0928 \u0905\u0902\u0918\u094b\u0933 \u0915\u0930\u0942\u0928 \u092b\u094d\u0930\u0947\u0936 \u091d\u093e\u0932\u0940 \u092e\u092e\u094d\u092e\u0940 \u0932\u093e \u0918\u0930 \u0906\u0935\u0930\u093e\u092f\u0932\u093e \u092e\u0926\u0924 \u0915\u0930\u0942 \u0932\u093e\u0917\u0932\u0940 \u092e\u092e\u094d\u092e\u0940 \u092a\u092a\u094d\u092a\u093e \u0915\u093e\u092e\u093e\u0935\u0930 \u0917\u0947\u0932\u094d\u092f\u093e\u0935\u0930 \u092e\u093e\u092e\u0940 \u0924\u093f\u091a\u093e \u092e\u0941\u0932\u093e\u0932\u093e \u0909\u0920\u0935\u093e\u092f\u0932\u093e \u0930\u0942\u092e \u092e\u0927\u0947 \u0906\u0932\u0940 \u0924\u094d\u092f\u093e\u0932\u093e \u0909\u0920\u0935\u0942\u0928 \u0905\u0902\u0918\u094b\u0933\u0940\u0932\u093e \u092a\u093e\u0920\u0935\u0932\u0902 \u0906\u0923\u093f \u092e\u093e\u091d\u0915\u0921 \u0906\u0932\u0940 \u092e\u0940 \u091d\u094b\u092a\u0932\u094b \u0939\u094b\u0924\u094b \u0924\u094b\u0902\u0921\u093e\u0935\u0930 \u0939\u093e\u0924 \u092b\u093f\u0930\u0935\u0942 \u0932\u093e\u0917\u0932\u0940 \u0915\u093f\u0938 \u0915\u0930\u0942 \u0932\u093e\u0917\u0932\u0940 i love you \u092c\u094b\u0932\u0942\u0928 \u092e\u0932\u093e \u092c\u094b\u0932\u0932\u0940 \u092e\u0940 \u0924\u0941\u091d\u093e \u092a\u094d\u0930\u0947\u092e\u093e\u0924 \u092a\u0921\u0932\u0947 \u0924\u093f\u0932\u093e \u0935\u093e\u091f\u0932\u0902 \u092e\u0940 \u0917\u093e\u0930 \u091d\u094b\u092a\u0947\u0924 \u0906\u0939\u0947 \u092a\u0923 \u092e\u0940 \u0938\u0917\u0933 \u0910\u0915\u0924 \u0939\u094b\u0924\u094b \u092e\u0940 \u0909\u0920\u0932\u094b \u0924\u0940 \u092e\u093e\u091d\u093e \u0917\u0933\u094d\u092f\u093e\u0924 \u092a\u0921\u0932\u0940 <\/p>\n\n\n\n<p>\u0906\u0923\u093f \u092e\u094d\u0939\u091f\u0932\u0940 \u092e\u0940 \u0906\u091c \u0916\u0942\u092a \u091c\u093e\u0938\u094d\u0924 \u0916\u0942\u0937 \u0906\u0939\u0947 \u0915\u093e\u0932\u091a\u0940 \u0930\u093e\u0924\u094d\u0930 \u0905\u0935\u093f\u0938\u094d\u092e\u0930\u0923\u0940\u092f \u0915\u094d\u0937\u0923 \u0939\u094b\u0924\u093e \u092e\u093e\u091d\u093e\u0938\u093e\u0920\u0940 \u0924\u0940 \u0916\u0942\u092a \u0939\u0949\u091f \u0926\u093f\u0938\u0924 \u0939\u094b\u0924\u0940 \u0924\u093f\u0928\u0947 \u0924\u0940\u091a \u0932\u093e\u0932 \u0938\u093e\u0921\u0940 \u0917\u094b\u0932\u094d\u0921\u0928 \u092c\u0949\u0930\u094d\u0921\u0930 \u0905\u0938\u0932\u0947\u0932\u0940 \u0906\u0923\u093f \u0939\u093f\u0930\u0935 \u092c\u094d\u0932\u093e\u0909\u0938 \u0913\u092a\u0928 \u092a\u093e\u0920\u0940\u091a \u0918\u093e\u0924\u0932\u0902 \u0939\u094b\u0924 \u0916\u0942\u092a \u091b\u093e\u0928 \u0926\u093f\u0938\u0924 \u0939\u094b\u0924\u0940 \u0938\u0927\u094d\u092f\u093e \u092e\u0947\u0915\u0905\u092a \u092e\u0927\u0947 \u092e\u0940 \u092a\u093e\u0939\u0942\u0928 \u092e\u094d\u0939\u091f\u0932\u0902 \u091a\u0932 \u0928\u093e \u092e\u0917 \u0906\u0924\u093e \u092a\u0930\u0924 \u0924\u0940 \u0939\u0938\u0932\u0940 \u0906\u0923\u093f \u092e\u094d\u0939\u091f\u0932\u0940 \u0906\u091c \u092a\u0942\u0930\u094d\u0923 \u0926\u093f\u0935\u0938 \u092a\u0921\u0932\u093e\u092f \u0906\u092a\u0932\u094d\u092f\u093e \u0915\u0921 \u092c\u092c\u0932\u0941 \u092c\u093e\u0939\u0947\u0930 \u091c\u093e\u0908\u0932 \u0916\u0947\u0933\u093e\u092f\u0932\u093e \u0924\u0947\u0935\u094d\u0939\u093e \u092e\u093e\u092e\u093e \u0939\u0940 \u0909\u0926\u094d\u092f\u093e \u092f\u0947\u0923\u093e\u0930 \u0906\u0939\u0947\u0924 \u0924\u093f\u0928\u0947 \u0924\u0938\u0902 \u092c\u094b\u0932\u0942\u0928 \u092e\u0932\u093e \u0921\u094b\u0933\u093e \u092e\u093e\u0930\u0932\u093e <\/p>\n\n\n\n<p>\u0906\u0923\u093f \u091b\u094b\u091f\u0940 \u0917\u093e\u0932\u093e\u0935\u0930 \u092a\u092a\u094d\u092a\u0940 \u0918\u0947\u090a\u0928 \u092e\u0932\u093e \u0905\u0902\u0918\u094b\u0933\u093f\u0932\u093e \u092a\u093e\u0923\u0940 \u0926\u093f\u0932\u0902 \u0906\u0935\u0930\u0942\u0928 \u092f\u093e \u092c\u094b\u0932\u0932\u0940 \u092e\u0940 \u0935\u093e\u091f \u092a\u093e\u0939\u0924\u0947 \u0924\u094d\u092f\u093e \u0926\u093f\u0935\u0936\u0940 \u092e\u0940 \u0926\u093f\u0935\u0938 \u092d\u0930 \u092e\u093e\u092e\u0940 \u0938\u094b\u092c\u0924 \u090f\u0915\u091f\u093e\u091a \u0939\u094b\u0924\u094b \u0906\u092e\u094d\u0939\u0940 \u0938\u0917\u0933\u0947 \u092a\u094b\u091d\u093f\u0936\u0928 \u091f\u094d\u0930\u093e\u092f \u0915\u0947\u0932\u0947 \u092e\u0928 \u092d\u0930\u0942\u0928 \u0938\u0947\u0915\u094d\u0938 \u0915\u093f\u0938 \u0938\u0917\u0933 \u0915\u0947\u0932\u0902 \u0906\u0923\u093f \u0924\u094d\u092f\u093e \u0926\u093f\u0935\u0938\u093e \u0928\u0902\u0924\u0930 \u092e\u093e\u091d\u0902 \u0906\u0923\u093f \u092e\u093e\u092e\u0940\u091a \u0928\u093e\u0924\u0902 \u092e\u093e\u092e\u0940 \u092d\u093e\u091a\u093e \u091a\u093e \u092a\u0932\u0940\u0915\u0921\u0947 \u0917\u0947\u0932 \u0906\u0924\u093e \u091c\u0947\u0935\u094d\u0939\u093e \u092e\u093e\u092e\u093e \u092c\u093e\u0939\u0947\u0930 \u091c\u093e\u0923\u093e\u0930 \u0905\u0938\u0924\u094b \u092e\u093e\u092e\u0940 \u092e\u093e\u092e\u093e \u0932\u093e \u0938\u093e\u0902\u0917\u0942\u0928 \u092e\u0932\u093e \u092c\u094b\u0932\u0935\u0942\u0928 \u0918\u0947\u0924\u0940 \u0906\u092e\u094d\u0939\u0940 \u0916\u0942\u092a \u092e\u091c\u094d\u091c\u093e \u0915\u0930\u0924 \u0905\u0938\u0924\u094b \u092e\u093e\u092e\u0940 \u0906\u0924\u093e \u092e\u093e\u091d\u093e \u0939\u093e\u0924\u093e\u0928\u0947 \u0938\u093f\u0928\u094d\u0926\u0941\u0930 \u0932\u093e\u090a\u0928 \u092e\u093e\u091d\u093e \u0939\u093e\u0924\u093e\u0928\u0947\u091a \u092e\u0902\u0917\u0933\u0938\u0942\u0924\u094d\u0930 \u0939\u0940 \u0918\u093e\u0932\u0924\u0947 \u0924\u0940 \u0928\u0935\u0931\u094d\u092f\u093e \u092a\u0947\u0915\u094d\u0937\u093e \u092e\u0932\u093e \u091c\u0935\u0933 \u091a\u093e \u0938\u092e\u091c\u0924\u0947 \u092e\u093e\u092e\u0940 \u0906\u0923\u093f \u092e\u0940 \u0926\u094b\u0918 \u0939\u0940 \u0928\u0935\u0930\u093e \u092c\u093e\u092f\u0915\u094b \u0938\u093e\u0930\u0916\u091a \u0935\u093e\u0917\u0924\u094b \u0906\u0924\u093e \u092f\u093e \u092a\u0941\u0922\u091a\u0940 \u092c\u093e\u0915\u0940 \u0917\u094b\u0937\u094d\u091f \u0926\u0941\u0938\u0931\u094d\u092f\u093e \u092a\u093e\u0930\u094d\u091f \u092e\u0927\u0947 \u0938\u093e\u0902\u0917\u0923 \u091c\u0947\u0935\u094d\u0939\u093e \u092e\u093e\u092e\u0940 \u091a\u0940 \u092b\u094d\u0930\u0947\u0902\u0921 \u0906\u092e\u091a\u0924 \u0925\u094d\u0930\u0940 \u0938\u092e \u0932\u093e \u0906\u0932\u0940 \u0906\u0923\u093f \u0924\u0940 \u0926\u0941\u0938\u0930\u0940 \u0915\u094b\u0923 \u0928\u093e\u0939\u0940 \u0924\u0930 \u092e\u093e\u091d\u093e\u091a \u091a\u0941\u0932\u0924 \u092e\u093e\u092e\u093e \u091a\u0940 \u092e\u0941\u0932\u0917\u0940 \u0924\u0928\u0941 \u0939\u094b\u0924\u0940 20 \u0935\u0930\u094d\u0937\u093e\u091a\u0940\u00a0<\/p>\n\n\n\n<p>\u0917\u094b\u0937\u094d\u091f \u0906\u0935\u0921\u0932\u094d\u092f\u093e\u0938 \u092e\u0932\u093e \u092e\u0947\u0932 \u0915\u0930\u0942\u0928 \u0930\u093f\u0938\u094d\u092a\u0949\u0928\u094d\u0938 \u0926\u094d\u092f\u093e \u0906\u0923\u093f \u0905\u0939\u093f\u0932\u094d\u092f\u093e\u0928\u0917\u0930 \u092e\u0927\u094d\u092f\u0947 \u0915\u094b\u0923\u093e\u0932\u093e \u0939\u0940 \u092e\u093e\u091d\u0940 \u0917\u0930\u091c \u092a\u0921\u0932\u0940 \u092e\u0941\u0932\u0940\u0932\u093e \u092c\u093e\u0908\u0932\u093e \u0924\u0930 \u092e\u0947\u0932 \u0915\u0930\u093e \u0938\u0917\u0933 \u0915\u093e\u0939\u0940 \u092a\u094d\u0930\u093e\u092f\u0935\u094d\u0939\u0947\u091f \u0930\u093e\u0939\u0940\u0932 \u0939\u093e \u092a\u094d\u0930\u0949\u092e\u093f\u0938 \u0906\u0939\u0947 \u0924\u0941\u092e\u094d\u0939\u093e\u0932\u093e&nbsp;<a href=\"mailto:adagaleshubham03@gmail.com\">adagaleshubham03@gmail.com<\/a>&nbsp;\u0935\u0930 \u0939\u094b \u092a\u0923 \u092a\u0941\u0922\u091a\u093e \u092a\u093e\u0930\u094d\u091f \u0938\u093e\u0920\u0940 \u0915\u0933\u0935\u093e \u0928\u0915\u094d\u0915\u0940 \u092e\u0932\u093e&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"704\" height=\"639\" src=\"https:\/\/www.marathit.com\/sex-story\/wp-content\/uploads\/2025\/11\/1000131204.png\" alt=\"\" class=\"wp-image-11126\" style=\"width:454px;height:auto\" srcset=\"https:\/\/www.marathit.com\/sex-story\/wp-content\/uploads\/2025\/11\/1000131204.png 704w, https:\/\/www.marathit.com\/sex-story\/wp-content\/uploads\/2025\/11\/1000131204-300x272.png 300w\" sizes=\"auto, (max-width: 704px) 100vw, 704px\" \/><\/figure>\n<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_11125\" class=\"pvc_stats total_only  \" data-element-id=\"11125\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.marathit.com\/sex-story\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div><div id=\"marat-1465365615\" class=\"marat-racer marat-entity-placement\"><script src=\"https:\/\/pubonrace.com\/e\/base36\/3170yrrp0ly6ka7k92i9dxd7denyplvlcojjs04q41?width=240&height=400\" async type=\"text\/javascript\" charset=\"UTF-8\"><\/script><\/div><div id=\"marat-358444200\" class=\"marat-after-content-2 marat-entity-placement\"><script type=\"text\/javascript\" src=\"https:\/\/hotbxeyira.today\/process.js?id=1456619249&p1=sub1&p2=sub2&p3=sub3&p4=sub4\" async> <\/script><\/div><div class=\"pld-like-dislike-wrap pld-custom\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"\" data-post-id=\"11125\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\">\r\n                            <img src=\"https:\/\/www.marathit.com\/sex-story\/wp-content\/uploads\/2023\/01\/icons8-like-64.png\" alt=\"\" \/>\r\n            <\/a>\r\n    <span class=\"pld-like-count-wrap pld-count-wrap\">2    <\/span>\r\n<\/div><div class=\"pld-dislike-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-dislike-trigger pld-like-dislike-trigger  \" title=\"\" data-post-id=\"11125\" data-trigger-type=\"dislike\" data-restriction=\"cookie\" data-already-liked=\"0\">\r\n                            <img src=\"https:\/\/www.marathit.com\/sex-story\/wp-content\/uploads\/2023\/01\/dislike-page.png\" alt=\"\" \/>\r\n            <\/a>\r\n    <span class=\"pld-dislike-count-wrap pld-count-wrap\">1<\/span>\r\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>\u0928\u092e\u0938\u094d\u0915\u093e\u0930 \u092e\u093f\u0924\u094d\u0930\u093e\u0928\u094b \u092e\u093e\u091d\u093e \u092e\u093e\u0917\u091a\u093e \u0926\u094b\u0928 \u0938\u094d\u091f\u094b\u0930\u0940\u0928\u093e \u091a\u093e\u0902\u0917\u0932\u093e \u092a\u094d\u0930\u0924\u093f\u0938\u093e\u0926 \u0926\u093f\u0932\u094d\u092f\u093e\u092c\u0926\u094d\u0926\u0932 \u0927\u0928\u094d\u092f\u0935\u093e\u0926 \u090f\u0915 \u0928\u0935\u0940\u0928 \u0938\u094d\u091f\u094b\u0930\u0940 \u0918\u0947\u090a\u0928 \u0906\u0932\u094b\u092f \u0924\u0941\u092e\u091a\u093e \u0938\u093e\u0920\u0940 \u092e\u093e\u091d\u0902 \u0928\u093e\u0935 \u0936\u0941\u092d\u092e \u092e\u0940 \u0905\u0939\u093f\u0932\u094d\u092f\u093e\u0928\u0917\u0930 \u091a\u093e \u0906\u0939\u0947 \u092e\u0932\u093e<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[605],"tags":[],"class_list":["post-11125","post","type-post","status-publish","format-standard","hentry","category-mami-"],"a3_pvc":{"activated":true,"total_views":16967,"today_views":10},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u092e\u093e\u092e\u0940 \u092c\u0928\u0932\u0940 \u092c\u093e\u092f\u0915\u094b<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.marathit.com\/sex-story\/\u092e\u093e\u092e\u0940-\u092c\u0928\u0932\u0940-\u092c\u093e\u092f\u0915\u094b-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u092e\u093e\u092e\u0940 \u092c\u0928\u0932\u0940 \u092c\u093e\u092f\u0915\u094b\" \/>\n<meta property=\"og:description\" content=\"\u0928\u092e\u0938\u094d\u0915\u093e\u0930 \u092e\u093f\u0924\u094d\u0930\u093e\u0928\u094b \u092e\u093e\u091d\u093e \u092e\u093e\u0917\u091a\u093e \u0926\u094b\u0928 \u0938\u094d\u091f\u094b\u0930\u0940\u0928\u093e \u091a\u093e\u0902\u0917\u0932\u093e \u092a\u094d\u0930\u0924\u093f\u0938\u093e\u0926 \u0926\u093f\u0932\u094d\u092f\u093e\u092c\u0926\u094d\u0926\u0932 \u0927\u0928\u094d\u092f\u0935\u093e\u0926 \u090f\u0915 \u0928\u0935\u0940\u0928 \u0938\u094d\u091f\u094b\u0930\u0940 \u0918\u0947\u090a\u0928 \u0906\u0932\u094b\u092f \u0924\u0941\u092e\u091a\u093e \u0938\u093e\u0920\u0940 \u092e\u093e\u091d\u0902 \u0928\u093e\u0935 \u0936\u0941\u092d\u092e \u092e\u0940 \u0905\u0939\u093f\u0932\u094d\u092f\u093e\u0928\u0917\u0930 \u091a\u093e \u0906\u0939\u0947 \u092e\u0932\u093e\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.marathit.com\/sex-story\/\u092e\u093e\u092e\u0940-\u092c\u0928\u0932\u0940-\u092c\u093e\u092f\u0915\u094b-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Marathi Sex Story\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-10T05:28:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-10T05:28:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.marathit.com\/sex-story\/wp-content\/uploads\/2025\/11\/1000131204.png\" \/>\n\t<meta property=\"og:image:width\" content=\"704\" \/>\n\t<meta property=\"og:image:height\" content=\"639\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"New User\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"New User\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/%e0%a4%ae%e0%a4%be%e0%a4%ae%e0%a5%80-%e0%a4%ac%e0%a4%a8%e0%a4%b2%e0%a5%80-%e0%a4%ac%e0%a4%be%e0%a4%af%e0%a4%95%e0%a5%8b-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/%e0%a4%ae%e0%a4%be%e0%a4%ae%e0%a5%80-%e0%a4%ac%e0%a4%a8%e0%a4%b2%e0%a5%80-%e0%a4%ac%e0%a4%be%e0%a4%af%e0%a4%95%e0%a5%8b-2\\\/\"},\"author\":{\"name\":\"New User\",\"@id\":\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/#\\\/schema\\\/person\\\/333f9723decc685673405097840867a1\"},\"headline\":\"\u092e\u093e\u092e\u0940 \u092c\u0928\u0932\u0940 \u092c\u093e\u092f\u0915\u094b\",\"datePublished\":\"2025-11-10T05:28:19+00:00\",\"dateModified\":\"2025-11-10T05:28:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/%e0%a4%ae%e0%a4%be%e0%a4%ae%e0%a5%80-%e0%a4%ac%e0%a4%a8%e0%a4%b2%e0%a5%80-%e0%a4%ac%e0%a4%be%e0%a4%af%e0%a4%95%e0%a5%8b-2\\\/\"},\"wordCount\":17,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/#\\\/schema\\\/person\\\/333f9723decc685673405097840867a1\"},\"image\":{\"@id\":\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/%e0%a4%ae%e0%a4%be%e0%a4%ae%e0%a5%80-%e0%a4%ac%e0%a4%a8%e0%a4%b2%e0%a5%80-%e0%a4%ac%e0%a4%be%e0%a4%af%e0%a4%95%e0%a5%8b-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/1000131204.png\",\"articleSection\":[\"Mami (\u092e\u093e\u092e\u0940)\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/%e0%a4%ae%e0%a4%be%e0%a4%ae%e0%a5%80-%e0%a4%ac%e0%a4%a8%e0%a4%b2%e0%a5%80-%e0%a4%ac%e0%a4%be%e0%a4%af%e0%a4%95%e0%a5%8b-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/%e0%a4%ae%e0%a4%be%e0%a4%ae%e0%a5%80-%e0%a4%ac%e0%a4%a8%e0%a4%b2%e0%a5%80-%e0%a4%ac%e0%a4%be%e0%a4%af%e0%a4%95%e0%a5%8b-2\\\/\",\"url\":\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/%e0%a4%ae%e0%a4%be%e0%a4%ae%e0%a5%80-%e0%a4%ac%e0%a4%a8%e0%a4%b2%e0%a5%80-%e0%a4%ac%e0%a4%be%e0%a4%af%e0%a4%95%e0%a5%8b-2\\\/\",\"name\":\"\u092e\u093e\u092e\u0940 \u092c\u0928\u0932\u0940 \u092c\u093e\u092f\u0915\u094b\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/%e0%a4%ae%e0%a4%be%e0%a4%ae%e0%a5%80-%e0%a4%ac%e0%a4%a8%e0%a4%b2%e0%a5%80-%e0%a4%ac%e0%a4%be%e0%a4%af%e0%a4%95%e0%a5%8b-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/%e0%a4%ae%e0%a4%be%e0%a4%ae%e0%a5%80-%e0%a4%ac%e0%a4%a8%e0%a4%b2%e0%a5%80-%e0%a4%ac%e0%a4%be%e0%a4%af%e0%a4%95%e0%a5%8b-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/1000131204.png\",\"datePublished\":\"2025-11-10T05:28:19+00:00\",\"dateModified\":\"2025-11-10T05:28:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/%e0%a4%ae%e0%a4%be%e0%a4%ae%e0%a5%80-%e0%a4%ac%e0%a4%a8%e0%a4%b2%e0%a5%80-%e0%a4%ac%e0%a4%be%e0%a4%af%e0%a4%95%e0%a5%8b-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/%e0%a4%ae%e0%a4%be%e0%a4%ae%e0%a5%80-%e0%a4%ac%e0%a4%a8%e0%a4%b2%e0%a5%80-%e0%a4%ac%e0%a4%be%e0%a4%af%e0%a4%95%e0%a5%8b-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/%e0%a4%ae%e0%a4%be%e0%a4%ae%e0%a5%80-%e0%a4%ac%e0%a4%a8%e0%a4%b2%e0%a5%80-%e0%a4%ac%e0%a4%be%e0%a4%af%e0%a4%95%e0%a5%8b-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/1000131204.png\",\"contentUrl\":\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/1000131204.png\",\"width\":704,\"height\":639},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/%e0%a4%ae%e0%a4%be%e0%a4%ae%e0%a5%80-%e0%a4%ac%e0%a4%a8%e0%a4%b2%e0%a5%80-%e0%a4%ac%e0%a4%be%e0%a4%af%e0%a4%95%e0%a5%8b-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u092e\u093e\u092e\u0940 \u092c\u0928\u0932\u0940 \u092c\u093e\u092f\u0915\u094b\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/#website\",\"url\":\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/\",\"name\":\"Marathi Sex Story\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/#\\\/schema\\\/person\\\/333f9723decc685673405097840867a1\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/#\\\/schema\\\/person\\\/333f9723decc685673405097840867a1\",\"name\":\"New User\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/cropped-\u092e\u0930\u093e\u0920\u0940\u0924.\u0915\u0949\u092e-1.png\",\"url\":\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/cropped-\u092e\u0930\u093e\u0920\u0940\u0924.\u0915\u0949\u092e-1.png\",\"contentUrl\":\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/cropped-\u092e\u0930\u093e\u0920\u0940\u0924.\u0915\u0949\u092e-1.png\",\"width\":202,\"height\":49,\"caption\":\"New User\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/cropped-\u092e\u0930\u093e\u0920\u0940\u0924.\u0915\u0949\u092e-1.png\"},\"url\":\"https:\\\/\\\/www.marathit.com\\\/sex-story\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u092e\u093e\u092e\u0940 \u092c\u0928\u0932\u0940 \u092c\u093e\u092f\u0915\u094b","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.marathit.com\/sex-story\/\u092e\u093e\u092e\u0940-\u092c\u0928\u0932\u0940-\u092c\u093e\u092f\u0915\u094b-2\/","og_locale":"en_US","og_type":"article","og_title":"\u092e\u093e\u092e\u0940 \u092c\u0928\u0932\u0940 \u092c\u093e\u092f\u0915\u094b","og_description":"\u0928\u092e\u0938\u094d\u0915\u093e\u0930 \u092e\u093f\u0924\u094d\u0930\u093e\u0928\u094b \u092e\u093e\u091d\u093e \u092e\u093e\u0917\u091a\u093e \u0926\u094b\u0928 \u0938\u094d\u091f\u094b\u0930\u0940\u0928\u093e \u091a\u093e\u0902\u0917\u0932\u093e \u092a\u094d\u0930\u0924\u093f\u0938\u093e\u0926 \u0926\u093f\u0932\u094d\u092f\u093e\u092c\u0926\u094d\u0926\u0932 \u0927\u0928\u094d\u092f\u0935\u093e\u0926 \u090f\u0915 \u0928\u0935\u0940\u0928 \u0938\u094d\u091f\u094b\u0930\u0940 \u0918\u0947\u090a\u0928 \u0906\u0932\u094b\u092f \u0924\u0941\u092e\u091a\u093e \u0938\u093e\u0920\u0940 \u092e\u093e\u091d\u0902 \u0928\u093e\u0935 \u0936\u0941\u092d\u092e \u092e\u0940 \u0905\u0939\u093f\u0932\u094d\u092f\u093e\u0928\u0917\u0930 \u091a\u093e \u0906\u0939\u0947 \u092e\u0932\u093e","og_url":"https:\/\/www.marathit.com\/sex-story\/\u092e\u093e\u092e\u0940-\u092c\u0928\u0932\u0940-\u092c\u093e\u092f\u0915\u094b-2\/","og_site_name":"Marathi Sex Story","article_published_time":"2025-11-10T05:28:19+00:00","article_modified_time":"2025-11-10T05:28:32+00:00","og_image":[{"width":704,"height":639,"url":"https:\/\/www.marathit.com\/sex-story\/wp-content\/uploads\/2025\/11\/1000131204.png","type":"image\/png"}],"author":"New User","twitter_card":"summary_large_image","twitter_misc":{"Written by":"New User","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.marathit.com\/sex-story\/%e0%a4%ae%e0%a4%be%e0%a4%ae%e0%a5%80-%e0%a4%ac%e0%a4%a8%e0%a4%b2%e0%a5%80-%e0%a4%ac%e0%a4%be%e0%a4%af%e0%a4%95%e0%a5%8b-2\/#article","isPartOf":{"@id":"https:\/\/www.marathit.com\/sex-story\/%e0%a4%ae%e0%a4%be%e0%a4%ae%e0%a5%80-%e0%a4%ac%e0%a4%a8%e0%a4%b2%e0%a5%80-%e0%a4%ac%e0%a4%be%e0%a4%af%e0%a4%95%e0%a5%8b-2\/"},"author":{"name":"New User","@id":"https:\/\/www.marathit.com\/sex-story\/#\/schema\/person\/333f9723decc685673405097840867a1"},"headline":"\u092e\u093e\u092e\u0940 \u092c\u0928\u0932\u0940 \u092c\u093e\u092f\u0915\u094b","datePublished":"2025-11-10T05:28:19+00:00","dateModified":"2025-11-10T05:28:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.marathit.com\/sex-story\/%e0%a4%ae%e0%a4%be%e0%a4%ae%e0%a5%80-%e0%a4%ac%e0%a4%a8%e0%a4%b2%e0%a5%80-%e0%a4%ac%e0%a4%be%e0%a4%af%e0%a4%95%e0%a5%8b-2\/"},"wordCount":17,"commentCount":2,"publisher":{"@id":"https:\/\/www.marathit.com\/sex-story\/#\/schema\/person\/333f9723decc685673405097840867a1"},"image":{"@id":"https:\/\/www.marathit.com\/sex-story\/%e0%a4%ae%e0%a4%be%e0%a4%ae%e0%a5%80-%e0%a4%ac%e0%a4%a8%e0%a4%b2%e0%a5%80-%e0%a4%ac%e0%a4%be%e0%a4%af%e0%a4%95%e0%a5%8b-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.marathit.com\/sex-story\/wp-content\/uploads\/2025\/11\/1000131204.png","articleSection":["Mami (\u092e\u093e\u092e\u0940)"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.marathit.com\/sex-story\/%e0%a4%ae%e0%a4%be%e0%a4%ae%e0%a5%80-%e0%a4%ac%e0%a4%a8%e0%a4%b2%e0%a5%80-%e0%a4%ac%e0%a4%be%e0%a4%af%e0%a4%95%e0%a5%8b-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.marathit.com\/sex-story\/%e0%a4%ae%e0%a4%be%e0%a4%ae%e0%a5%80-%e0%a4%ac%e0%a4%a8%e0%a4%b2%e0%a5%80-%e0%a4%ac%e0%a4%be%e0%a4%af%e0%a4%95%e0%a5%8b-2\/","url":"https:\/\/www.marathit.com\/sex-story\/%e0%a4%ae%e0%a4%be%e0%a4%ae%e0%a5%80-%e0%a4%ac%e0%a4%a8%e0%a4%b2%e0%a5%80-%e0%a4%ac%e0%a4%be%e0%a4%af%e0%a4%95%e0%a5%8b-2\/","name":"\u092e\u093e\u092e\u0940 \u092c\u0928\u0932\u0940 \u092c\u093e\u092f\u0915\u094b","isPartOf":{"@id":"https:\/\/www.marathit.com\/sex-story\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.marathit.com\/sex-story\/%e0%a4%ae%e0%a4%be%e0%a4%ae%e0%a5%80-%e0%a4%ac%e0%a4%a8%e0%a4%b2%e0%a5%80-%e0%a4%ac%e0%a4%be%e0%a4%af%e0%a4%95%e0%a5%8b-2\/#primaryimage"},"image":{"@id":"https:\/\/www.marathit.com\/sex-story\/%e0%a4%ae%e0%a4%be%e0%a4%ae%e0%a5%80-%e0%a4%ac%e0%a4%a8%e0%a4%b2%e0%a5%80-%e0%a4%ac%e0%a4%be%e0%a4%af%e0%a4%95%e0%a5%8b-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.marathit.com\/sex-story\/wp-content\/uploads\/2025\/11\/1000131204.png","datePublished":"2025-11-10T05:28:19+00:00","dateModified":"2025-11-10T05:28:32+00:00","breadcrumb":{"@id":"https:\/\/www.marathit.com\/sex-story\/%e0%a4%ae%e0%a4%be%e0%a4%ae%e0%a5%80-%e0%a4%ac%e0%a4%a8%e0%a4%b2%e0%a5%80-%e0%a4%ac%e0%a4%be%e0%a4%af%e0%a4%95%e0%a5%8b-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.marathit.com\/sex-story\/%e0%a4%ae%e0%a4%be%e0%a4%ae%e0%a5%80-%e0%a4%ac%e0%a4%a8%e0%a4%b2%e0%a5%80-%e0%a4%ac%e0%a4%be%e0%a4%af%e0%a4%95%e0%a5%8b-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.marathit.com\/sex-story\/%e0%a4%ae%e0%a4%be%e0%a4%ae%e0%a5%80-%e0%a4%ac%e0%a4%a8%e0%a4%b2%e0%a5%80-%e0%a4%ac%e0%a4%be%e0%a4%af%e0%a4%95%e0%a5%8b-2\/#primaryimage","url":"https:\/\/www.marathit.com\/sex-story\/wp-content\/uploads\/2025\/11\/1000131204.png","contentUrl":"https:\/\/www.marathit.com\/sex-story\/wp-content\/uploads\/2025\/11\/1000131204.png","width":704,"height":639},{"@type":"BreadcrumbList","@id":"https:\/\/www.marathit.com\/sex-story\/%e0%a4%ae%e0%a4%be%e0%a4%ae%e0%a5%80-%e0%a4%ac%e0%a4%a8%e0%a4%b2%e0%a5%80-%e0%a4%ac%e0%a4%be%e0%a4%af%e0%a4%95%e0%a5%8b-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.marathit.com\/sex-story\/"},{"@type":"ListItem","position":2,"name":"\u092e\u093e\u092e\u0940 \u092c\u0928\u0932\u0940 \u092c\u093e\u092f\u0915\u094b"}]},{"@type":"WebSite","@id":"https:\/\/www.marathit.com\/sex-story\/#website","url":"https:\/\/www.marathit.com\/sex-story\/","name":"Marathi Sex Story","description":"","publisher":{"@id":"https:\/\/www.marathit.com\/sex-story\/#\/schema\/person\/333f9723decc685673405097840867a1"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.marathit.com\/sex-story\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.marathit.com\/sex-story\/#\/schema\/person\/333f9723decc685673405097840867a1","name":"New User","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.marathit.com\/sex-story\/wp-content\/uploads\/2025\/10\/cropped-\u092e\u0930\u093e\u0920\u0940\u0924.\u0915\u0949\u092e-1.png","url":"https:\/\/www.marathit.com\/sex-story\/wp-content\/uploads\/2025\/10\/cropped-\u092e\u0930\u093e\u0920\u0940\u0924.\u0915\u0949\u092e-1.png","contentUrl":"https:\/\/www.marathit.com\/sex-story\/wp-content\/uploads\/2025\/10\/cropped-\u092e\u0930\u093e\u0920\u0940\u0924.\u0915\u0949\u092e-1.png","width":202,"height":49,"caption":"New User"},"logo":{"@id":"https:\/\/www.marathit.com\/sex-story\/wp-content\/uploads\/2025\/10\/cropped-\u092e\u0930\u093e\u0920\u0940\u0924.\u0915\u0949\u092e-1.png"},"url":"https:\/\/www.marathit.com\/sex-story\/author\/admin\/"}]}},"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"New User","author_link":"https:\/\/www.marathit.com\/sex-story\/author\/admin\/"},"rttpg_comment":2,"rttpg_category":"<a href=\"https:\/\/www.marathit.com\/sex-story\/category\/mami-%e0%a4%ae%e0%a4%be%e0%a4%ae%e0%a5%80\/\" rel=\"category tag\">Mami (\u092e\u093e\u092e\u0940)<\/a>","rttpg_excerpt":"\u0928\u092e\u0938\u094d\u0915\u093e\u0930 \u092e\u093f\u0924\u094d\u0930\u093e\u0928\u094b \u092e\u093e\u091d\u093e \u092e\u093e\u0917\u091a\u093e \u0926\u094b\u0928 \u0938\u094d\u091f\u094b\u0930\u0940\u0928\u093e \u091a\u093e\u0902\u0917\u0932\u093e \u092a\u094d\u0930\u0924\u093f\u0938\u093e\u0926 \u0926\u093f\u0932\u094d\u092f\u093e\u092c\u0926\u094d\u0926\u0932 \u0927\u0928\u094d\u092f\u0935\u093e\u0926 \u090f\u0915 \u0928\u0935\u0940\u0928 \u0938\u094d\u091f\u094b\u0930\u0940 \u0918\u0947\u090a\u0928 \u0906\u0932\u094b\u092f \u0924\u0941\u092e\u091a\u093e \u0938\u093e\u0920\u0940 \u092e\u093e\u091d\u0902 \u0928\u093e\u0935 \u0936\u0941\u092d\u092e \u092e\u0940 \u0905\u0939\u093f\u0932\u094d\u092f\u093e\u0928\u0917\u0930 \u091a\u093e \u0906\u0939\u0947 \u092e\u0932\u093e","_links":{"self":[{"href":"https:\/\/www.marathit.com\/sex-story\/wp-json\/wp\/v2\/posts\/11125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.marathit.com\/sex-story\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.marathit.com\/sex-story\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.marathit.com\/sex-story\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marathit.com\/sex-story\/wp-json\/wp\/v2\/comments?post=11125"}],"version-history":[{"count":1,"href":"https:\/\/www.marathit.com\/sex-story\/wp-json\/wp\/v2\/posts\/11125\/revisions"}],"predecessor-version":[{"id":11127,"href":"https:\/\/www.marathit.com\/sex-story\/wp-json\/wp\/v2\/posts\/11125\/revisions\/11127"}],"wp:attachment":[{"href":"https:\/\/www.marathit.com\/sex-story\/wp-json\/wp\/v2\/media?parent=11125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.marathit.com\/sex-story\/wp-json\/wp\/v2\/categories?post=11125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.marathit.com\/sex-story\/wp-json\/wp\/v2\/tags?post=11125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}